{"id":130,"count":3,"description":"","link":"https:\/\/nearlearn.com\/blog\/tag\/online-training\/","name":"online training","slug":"online-training","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/nearlearn.com\/blog\/wp-json\/wp\/v2\/tags\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nearlearn.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nearlearn.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nearlearn.com\/blog\/wp-json\/wp\/v2\/posts?tags=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}