{"id":136,"count":2,"description":"","link":"https:\/\/nearlearn.com\/blog\/tag\/online-artificial-intelligence-course-in-india\/","name":"online artificial intelligence course in india","slug":"online-artificial-intelligence-course-in-india","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/nearlearn.com\/blog\/wp-json\/wp\/v2\/tags\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nearlearn.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nearlearn.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nearlearn.com\/blog\/wp-json\/wp\/v2\/posts?tags=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}